{"id":24966,"date":"2022-11-30T17:02:49","date_gmt":"2022-11-30T20:02:49","guid":{"rendered":"http:\/\/lojasosprofessoratividades.com.br\/?post_type=product&#038;p=24966"},"modified":"2026-05-08T17:09:36","modified_gmt":"2026-05-08T20:09:36","slug":"caixa-de-sabonete-90g","status":"publish","type":"product","link":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/caixa-de-sabonete-90g\/","title":{"rendered":"Caixa natalina para sabonete 90g"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Arquivo <em><strong>n\u00e3o<\/strong><\/em> edit\u00e1vel.<\/p>\n<p>Arte linda para sabonete 90g.<\/p>\n<p>Um presente gracioso de Natal.<\/p>\n<p>O arquivo traz a arte e imagens para voc\u00ea enfeitar a caixa.<\/p>\n<h3><em><strong>N\u00e3o enviamos por e-mail, a entrega \u00e9 via link para download.\u00a0<img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/16.0.1\/svg\/1f447.svg\" alt=\"\ud83d\udc47\" \/><\/strong><\/em><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-31375 size-full\" src=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/08\/Aviso-Loja.jpg\" alt=\"\" width=\"446\" height=\"251\" srcset=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/08\/Aviso-Loja.jpg 446w, https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/08\/Aviso-Loja-300x169.jpg 300w, https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/08\/Aviso-Loja-18x10.jpg 18w\" sizes=\"auto, (max-width: 446px) 100vw, 446px\" \/><\/p>","protected":false},"featured_media":24968,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[122,123,124,125,127,216,218,210,214,212],"product_tag":[864,863,3283,3287,869,867,3279,3284,3286,3238,3256,865,3285,3241,860,868,866],"class_list":{"0":"post-24966","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-1o-ano","7":"product_cat-2o-ano","8":"product_cat-3o-ano","9":"product_cat-4o-ano","10":"product_cat-5o-ano","11":"product_cat-data-comemorativa-4-ano","12":"product_cat-data-comemorativa-5-ano","13":"product_cat-data-comemorativa-1-ano","14":"product_cat-data-comemorativa-3-ano","15":"product_cat-data-comemorativa-2-ano","16":"product_tag-arte-decorativa","17":"product_tag-caixa-de-sabonete","18":"product_tag-caixa-de-sabonete-natal","19":"product_tag-caixa-para-imprimir-natal","20":"product_tag-decoracao-de-natal","21":"product_tag-embalagem-personalizada","22":"product_tag-embalagem-personalizada-natal","23":"product_tag-embalagem-sabonete-natal","24":"product_tag-lembrancinha-artesanal-natal","25":"product_tag-lembrancinha-natal","26":"product_tag-lembrancinha-natal-escolar","27":"product_tag-lembrancinha-natalina","28":"product_tag-molde-caixa-de-sabonete","29":"product_tag-presente-criativo-natal","30":"product_tag-presente-de-natal","31":"product_tag-presente-gracioso","32":"product_tag-sabonete-90g","34":"first","35":"instock","36":"downloadable","37":"virtual","38":"sold-individually","39":"purchasable","40":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caixa natalina para sabonete 90g - Loja SOS Professor Atividades<\/title>\n<meta name=\"description\" content=\"Encante neste Natal com a \u201cCaixa de Sabonete\u201d! Arte exclusiva para criar embalagens elegantes e personalizadas para sabonetes de 90g.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/caixa-de-sabonete-90g\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caixa natalina para sabonete 90g - Loja SOS Professor Atividades\" \/>\n<meta property=\"og:description\" content=\"Encante neste Natal com a \u201cCaixa de Sabonete\u201d! Arte exclusiva para criar embalagens elegantes e personalizadas para sabonetes de 90g.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/caixa-de-sabonete-90g\/\" \/>\n<meta property=\"og:site_name\" content=\"Loja SOS Professor Atividades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sosprofessoratividades\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T20:09:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/11\/1-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"693\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/caixa-de-sabonete-90g\\\/\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/caixa-de-sabonete-90g\\\/\",\"name\":\"Caixa natalina para sabonete 90g - Loja SOS Professor Atividades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/caixa-de-sabonete-90g\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/caixa-de-sabonete-90g\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/1-10.jpg\",\"datePublished\":\"2022-11-30T20:02:49+00:00\",\"dateModified\":\"2026-05-08T20:09:36+00:00\",\"description\":\"Encante neste Natal com a \u201cCaixa de Sabonete\u201d! Arte exclusiva para criar embalagens elegantes e personalizadas para sabonetes de 90g.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/caixa-de-sabonete-90g\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/caixa-de-sabonete-90g\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/caixa-de-sabonete-90g\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/1-10.jpg\",\"contentUrl\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/1-10.jpg\",\"width\":800,\"height\":693},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/caixa-de-sabonete-90g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Caixa natalina para sabonete 90g\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#website\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\",\"name\":\"Loja SOS Professor Atividades\",\"description\":\"Venda de material did\u00e1tico para o ensino fundamental\",\"publisher\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#organization\",\"name\":\"Loja SOS Professor Atividades\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo.png\",\"contentUrl\":\"http:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo.png\",\"width\":2000,\"height\":2000,\"caption\":\"Loja SOS Professor Atividades\"},\"image\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sosprofessoratividades\",\"https:\\\/\\\/www.instagram.com\\\/sosprofessoratividades\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caixa natalina para sabonete 90g - Loja SOS Professor Atividades","description":"Encante neste Natal com a \u201cCaixa de Sabonete\u201d! Arte exclusiva para criar embalagens elegantes e personalizadas para sabonetes de 90g.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/caixa-de-sabonete-90g\/","og_locale":"en_US","og_type":"article","og_title":"Caixa natalina para sabonete 90g - Loja SOS Professor Atividades","og_description":"Encante neste Natal com a \u201cCaixa de Sabonete\u201d! Arte exclusiva para criar embalagens elegantes e personalizadas para sabonetes de 90g.","og_url":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/caixa-de-sabonete-90g\/","og_site_name":"Loja SOS Professor Atividades","article_publisher":"https:\/\/www.facebook.com\/sosprofessoratividades","article_modified_time":"2026-05-08T20:09:36+00:00","og_image":[{"width":800,"height":693,"url":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/11\/1-10.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/caixa-de-sabonete-90g\/","url":"https:\/\/lojasosprofessoratividades.com.br\/produto\/caixa-de-sabonete-90g\/","name":"Caixa natalina para sabonete 90g - Loja SOS Professor Atividades","isPartOf":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/caixa-de-sabonete-90g\/#primaryimage"},"image":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/caixa-de-sabonete-90g\/#primaryimage"},"thumbnailUrl":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/11\/1-10.jpg","datePublished":"2022-11-30T20:02:49+00:00","dateModified":"2026-05-08T20:09:36+00:00","description":"Encante neste Natal com a \u201cCaixa de Sabonete\u201d! Arte exclusiva para criar embalagens elegantes e personalizadas para sabonetes de 90g.","breadcrumb":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/caixa-de-sabonete-90g\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lojasosprofessoratividades.com.br\/produto\/caixa-de-sabonete-90g\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/caixa-de-sabonete-90g\/#primaryimage","url":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/11\/1-10.jpg","contentUrl":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/11\/1-10.jpg","width":800,"height":693},{"@type":"BreadcrumbList","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/caixa-de-sabonete-90g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lojasosprofessoratividades.com.br\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/lojasosprofessoratividades.com.br\/loja\/"},{"@type":"ListItem","position":3,"name":"Caixa natalina para sabonete 90g"}]},{"@type":"WebSite","@id":"https:\/\/lojasosprofessoratividades.com.br\/#website","url":"https:\/\/lojasosprofessoratividades.com.br\/","name":"Loja SOS Professor Atividades","description":"Venda de material did\u00e1tico para o ensino fundamental","publisher":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lojasosprofessoratividades.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lojasosprofessoratividades.com.br\/#organization","name":"Loja SOS Professor Atividades","url":"https:\/\/lojasosprofessoratividades.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lojasosprofessoratividades.com.br\/#\/schema\/logo\/image\/","url":"http:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/04\/Logo.png","contentUrl":"http:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/04\/Logo.png","width":2000,"height":2000,"caption":"Loja SOS Professor Atividades"},"image":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sosprofessoratividades","https:\/\/www.instagram.com\/sosprofessoratividades\/"]}]}},"_links":{"self":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product\/24966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/comments?post=24966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/media\/24968"}],"wp:attachment":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/media?parent=24966"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_brand?post=24966"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=24966"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=24966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}