{"id":25307,"date":"2023-01-18T00:29:04","date_gmt":"2023-01-18T03:29:04","guid":{"rendered":"http:\/\/lojasosprofessoratividades.com.br\/?post_type=product&#038;p=25307"},"modified":"2026-05-08T16:58:08","modified_gmt":"2026-05-08T19:58:08","slug":"cartazes-2-turma-do-chaves","status":"publish","type":"product","link":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/cartazes-2-turma-do-chaves\/","title":{"rendered":"Cartazes 2 &#8211; Turma do Chaves"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Arquivo <em><strong>n\u00e3o<\/strong><\/em> edit\u00e1vel.<\/p>\n<p>S\u00e3o 6 (seis) cartazes de portugu\u00eas com os seguintes conte\u00fados gramaticais:<\/p>\n<ul>\n<li>divis\u00e3o sil\u00e1bica (n\u00famero de s\u00edlabas);<\/li>\n<li>s\u00edlaba t\u00f4nica;<\/li>\n<li>acentua\u00e7\u00e3o (acento agudo, circunflexo e grave);<\/li>\n<li>sinais de pontua\u00e7\u00e3o.<\/li>\n<\/ul>\n<p>Podem ser ampliados em tamanho p\u00f4ster ou reduzidos para colar no caderno dos alunos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-26942 size-full\" src=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/07\/aviso-novo-da-loja.png\" alt=\"\" width=\"446\" height=\"251\" srcset=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/07\/aviso-novo-da-loja.png 446w, https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/07\/aviso-novo-da-loja-300x169.png 300w, https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/07\/aviso-novo-da-loja-18x10.png 18w\" sizes=\"auto, (max-width: 446px) 100vw, 446px\" \/><\/p>","protected":false},"featured_media":25309,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[124,125,127,195,204,189,217,213,215],"product_tag":[],"class_list":{"0":"post-25307","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-3o-ano","7":"product_cat-4o-ano","8":"product_cat-5o-ano","9":"product_cat-portugues-4-ano","10":"product_cat-portugues-5-anos","11":"product_cat-portugues-3-ano","12":"product_cat-recursos-didaticos-5-ano","13":"product_cat-recursos-didaticos-3-ano","14":"product_cat-recursos-didaticos-4-ano","16":"first","17":"instock","18":"downloadable","19":"virtual","20":"purchasable","21":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cartazes 2 - Turma do Chaves - Loja SOS Professor Atividades<\/title>\n<meta name=\"description\" content=\"Cartazes de portugu\u00eas com a Turma do Chaves.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/cartazes-2-turma-do-chaves\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cartazes 2 - Turma do Chaves - Loja SOS Professor Atividades\" \/>\n<meta property=\"og:description\" content=\"Cartazes de portugu\u00eas com a Turma do Chaves.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/cartazes-2-turma-do-chaves\/\" \/>\n<meta property=\"og:site_name\" content=\"Loja SOS Professor Atividades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sosprofessoratividades\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T19:58:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/01\/1-4.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"693\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/cartazes-2-turma-do-chaves\\\/\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/cartazes-2-turma-do-chaves\\\/\",\"name\":\"Cartazes 2 - Turma do Chaves - Loja SOS Professor Atividades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/cartazes-2-turma-do-chaves\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/cartazes-2-turma-do-chaves\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/1-4.png\",\"datePublished\":\"2023-01-18T03:29:04+00:00\",\"dateModified\":\"2026-05-08T19:58:08+00:00\",\"description\":\"Cartazes de portugu\u00eas com a Turma do Chaves.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/cartazes-2-turma-do-chaves\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/cartazes-2-turma-do-chaves\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/cartazes-2-turma-do-chaves\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/1-4.png\",\"contentUrl\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/1-4.png\",\"width\":800,\"height\":693,\"caption\":\"cartazes 2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/cartazes-2-turma-do-chaves\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cartazes 2 &#8211; Turma do Chaves\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#website\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\",\"name\":\"Loja SOS Professor Atividades\",\"description\":\"Venda de material did\u00e1tico para o ensino fundamental\",\"publisher\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#organization\",\"name\":\"Loja SOS Professor Atividades\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo.png\",\"contentUrl\":\"http:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo.png\",\"width\":2000,\"height\":2000,\"caption\":\"Loja SOS Professor Atividades\"},\"image\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sosprofessoratividades\",\"https:\\\/\\\/www.instagram.com\\\/sosprofessoratividades\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cartazes 2 - Turma do Chaves - Loja SOS Professor Atividades","description":"Cartazes de portugu\u00eas com a Turma do Chaves.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/cartazes-2-turma-do-chaves\/","og_locale":"en_US","og_type":"article","og_title":"Cartazes 2 - Turma do Chaves - Loja SOS Professor Atividades","og_description":"Cartazes de portugu\u00eas com a Turma do Chaves.","og_url":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/cartazes-2-turma-do-chaves\/","og_site_name":"Loja SOS Professor Atividades","article_publisher":"https:\/\/www.facebook.com\/sosprofessoratividades","article_modified_time":"2026-05-08T19:58:08+00:00","og_image":[{"width":800,"height":693,"url":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/01\/1-4.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/cartazes-2-turma-do-chaves\/","url":"https:\/\/lojasosprofessoratividades.com.br\/produto\/cartazes-2-turma-do-chaves\/","name":"Cartazes 2 - Turma do Chaves - Loja SOS Professor Atividades","isPartOf":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/cartazes-2-turma-do-chaves\/#primaryimage"},"image":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/cartazes-2-turma-do-chaves\/#primaryimage"},"thumbnailUrl":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/01\/1-4.png","datePublished":"2023-01-18T03:29:04+00:00","dateModified":"2026-05-08T19:58:08+00:00","description":"Cartazes de portugu\u00eas com a Turma do Chaves.","breadcrumb":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/cartazes-2-turma-do-chaves\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lojasosprofessoratividades.com.br\/produto\/cartazes-2-turma-do-chaves\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/cartazes-2-turma-do-chaves\/#primaryimage","url":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/01\/1-4.png","contentUrl":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/01\/1-4.png","width":800,"height":693,"caption":"cartazes 2"},{"@type":"BreadcrumbList","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/cartazes-2-turma-do-chaves\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lojasosprofessoratividades.com.br\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/lojasosprofessoratividades.com.br\/loja\/"},{"@type":"ListItem","position":3,"name":"Cartazes 2 &#8211; Turma do Chaves"}]},{"@type":"WebSite","@id":"https:\/\/lojasosprofessoratividades.com.br\/#website","url":"https:\/\/lojasosprofessoratividades.com.br\/","name":"Loja SOS Professor Atividades","description":"Venda de material did\u00e1tico para o ensino fundamental","publisher":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lojasosprofessoratividades.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lojasosprofessoratividades.com.br\/#organization","name":"Loja SOS Professor Atividades","url":"https:\/\/lojasosprofessoratividades.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lojasosprofessoratividades.com.br\/#\/schema\/logo\/image\/","url":"http:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/04\/Logo.png","contentUrl":"http:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/04\/Logo.png","width":2000,"height":2000,"caption":"Loja SOS Professor Atividades"},"image":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sosprofessoratividades","https:\/\/www.instagram.com\/sosprofessoratividades\/"]}]}},"_links":{"self":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product\/25307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/comments?post=25307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/media\/25309"}],"wp:attachment":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/media?parent=25307"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_brand?post=25307"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=25307"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=25307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}