{"id":25703,"date":"2023-03-08T21:59:34","date_gmt":"2023-03-09T00:59:34","guid":{"rendered":"http:\/\/lojasosprofessoratividades.com.br\/?post_type=product&#038;p=25703"},"modified":"2026-05-08T16:50:33","modified_gmt":"2026-05-08T19:50:33","slug":"circo-23","status":"publish","type":"product","link":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/circo-23\/","title":{"rendered":"Circo 23"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Arquivo com 25 p\u00e1ginas <em><strong>n\u00e3o<\/strong><\/em> edit\u00e1veis.<\/p>\n<p>Cont\u00e9m:<\/p>\n<ul>\n<li>Moldura para fotos;<\/li>\n<li>Coroas colorida e para pintar;<\/li>\n<li>Dois cartazes para ampliar;<\/li>\n<li>Todos os elementos presentes no cartaz j\u00e1 ampliados em 2 folhas A4 cada, com exce\u00e7\u00e3o do circo que est\u00e1 ampliado em 3 folhas A4;<\/li>\n<li>Bandeirinhas duas por folha A4.<\/li>\n<\/ul>\n<p>Dica: forre o fundo do seu mural\/painel com tiras de cartolinas coloridas ou use cartolina branca e pinte com tinta guache, o efeito fica lindo.<\/p>\n<h3>N\u00e3o enviamos por e-mail, a entrega \u00e9 via link para download. \ud83d\udc47<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-38009 size-full\" src=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2026\/02\/Como-baixar-2.jpg\" alt=\"\" width=\"446\" height=\"251\" srcset=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2026\/02\/Como-baixar-2.jpg 446w, https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2026\/02\/Como-baixar-2-300x169.jpg 300w, https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2026\/02\/Como-baixar-2-18x10.jpg 18w\" sizes=\"auto, (max-width: 446px) 100vw, 446px\" \/><\/p>","protected":false},"featured_media":25715,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[122,123,124,125,127,216,218,210,214,212],"product_tag":[1251,1249,447,1248,1246,1250,1247,540,906,1252],"class_list":{"0":"post-25703","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-1o-ano","7":"product_cat-2o-ano","8":"product_cat-3o-ano","9":"product_cat-4o-ano","10":"product_cat-5o-ano","11":"product_cat-data-comemorativa-4-ano","12":"product_cat-data-comemorativa-5-ano","13":"product_cat-data-comemorativa-1-ano","14":"product_cat-data-comemorativa-3-ano","15":"product_cat-data-comemorativa-2-ano","16":"product_tag-bandeirinhas-circo","17":"product_tag-cartaz-circo","18":"product_tag-circo","19":"product_tag-coroas-para-pintar","20":"product_tag-decoracao-circo","21":"product_tag-elementos-ampliados","22":"product_tag-festa-circo","23":"product_tag-material-educativo","24":"product_tag-moldura-para-fotos","25":"product_tag-tema-circo","27":"first","28":"instock","29":"downloadable","30":"virtual","31":"sold-individually","32":"purchasable","33":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Circo 23 - Loja SOS Professor Atividades<\/title>\n<meta name=\"description\" content=\"Arquivo Dia do Circo com moldura para fotos, coroas coloridas e para pintar, cartazes ampliados e bandeirinhas prontas para imprimir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/circo-23\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Circo 23 - Loja SOS Professor Atividades\" \/>\n<meta property=\"og:description\" content=\"Arquivo Dia do Circo com moldura para fotos, coroas coloridas e para pintar, cartazes ampliados e bandeirinhas prontas para imprimir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/circo-23\/\" \/>\n<meta property=\"og:site_name\" content=\"Loja SOS Professor Atividades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sosprofessoratividades\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T19:50:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/03\/1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"693\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/circo-23\\\/\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/circo-23\\\/\",\"name\":\"Circo 23 - Loja SOS Professor Atividades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/circo-23\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/circo-23\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1-2.jpg\",\"datePublished\":\"2023-03-09T00:59:34+00:00\",\"dateModified\":\"2026-05-08T19:50:33+00:00\",\"description\":\"Arquivo Dia do Circo com moldura para fotos, coroas coloridas e para pintar, cartazes ampliados e bandeirinhas prontas para imprimir.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/circo-23\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/circo-23\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/circo-23\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1-2.jpg\",\"width\":800,\"height\":693,\"caption\":\"circo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/circo-23\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Circo 23\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#website\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\",\"name\":\"Loja SOS Professor Atividades\",\"description\":\"Venda de material did\u00e1tico para o ensino fundamental\",\"publisher\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#organization\",\"name\":\"Loja SOS Professor Atividades\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo.png\",\"contentUrl\":\"http:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo.png\",\"width\":2000,\"height\":2000,\"caption\":\"Loja SOS Professor Atividades\"},\"image\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sosprofessoratividades\",\"https:\\\/\\\/www.instagram.com\\\/sosprofessoratividades\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Circo 23 - Loja SOS Professor Atividades","description":"Arquivo Dia do Circo com moldura para fotos, coroas coloridas e para pintar, cartazes ampliados e bandeirinhas prontas para imprimir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/circo-23\/","og_locale":"en_US","og_type":"article","og_title":"Circo 23 - Loja SOS Professor Atividades","og_description":"Arquivo Dia do Circo com moldura para fotos, coroas coloridas e para pintar, cartazes ampliados e bandeirinhas prontas para imprimir.","og_url":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/circo-23\/","og_site_name":"Loja SOS Professor Atividades","article_publisher":"https:\/\/www.facebook.com\/sosprofessoratividades","article_modified_time":"2026-05-08T19:50:33+00:00","og_image":[{"width":800,"height":693,"url":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/03\/1-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/circo-23\/","url":"https:\/\/lojasosprofessoratividades.com.br\/produto\/circo-23\/","name":"Circo 23 - Loja SOS Professor Atividades","isPartOf":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/circo-23\/#primaryimage"},"image":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/circo-23\/#primaryimage"},"thumbnailUrl":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/03\/1-2.jpg","datePublished":"2023-03-09T00:59:34+00:00","dateModified":"2026-05-08T19:50:33+00:00","description":"Arquivo Dia do Circo com moldura para fotos, coroas coloridas e para pintar, cartazes ampliados e bandeirinhas prontas para imprimir.","breadcrumb":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/circo-23\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lojasosprofessoratividades.com.br\/produto\/circo-23\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/circo-23\/#primaryimage","url":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/03\/1-2.jpg","contentUrl":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/03\/1-2.jpg","width":800,"height":693,"caption":"circo"},{"@type":"BreadcrumbList","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/circo-23\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lojasosprofessoratividades.com.br\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/lojasosprofessoratividades.com.br\/loja\/"},{"@type":"ListItem","position":3,"name":"Circo 23"}]},{"@type":"WebSite","@id":"https:\/\/lojasosprofessoratividades.com.br\/#website","url":"https:\/\/lojasosprofessoratividades.com.br\/","name":"Loja SOS Professor Atividades","description":"Venda de material did\u00e1tico para o ensino fundamental","publisher":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lojasosprofessoratividades.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lojasosprofessoratividades.com.br\/#organization","name":"Loja SOS Professor Atividades","url":"https:\/\/lojasosprofessoratividades.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lojasosprofessoratividades.com.br\/#\/schema\/logo\/image\/","url":"http:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/04\/Logo.png","contentUrl":"http:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/04\/Logo.png","width":2000,"height":2000,"caption":"Loja SOS Professor Atividades"},"image":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sosprofessoratividades","https:\/\/www.instagram.com\/sosprofessoratividades\/"]}]}},"_links":{"self":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product\/25703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/comments?post=25703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/media\/25715"}],"wp:attachment":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/media?parent=25703"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_brand?post=25703"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=25703"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=25703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}