{"id":25794,"date":"2023-03-30T07:00:55","date_gmt":"2023-03-30T10:00:55","guid":{"rendered":"http:\/\/lojasosprofessoratividades.com.br\/?post_type=product&#038;p=25794"},"modified":"2026-05-08T16:51:38","modified_gmt":"2026-05-08T19:51:38","slug":"pascoa-recheada","status":"publish","type":"product","link":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/pascoa-recheada\/","title":{"rendered":"P\u00e1scoa recheada"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>A celebra\u00e7\u00e3o da P\u00e1scoa na escola pode ser uma oportunidade valiosa para os alunos aprenderem sobre a hist\u00f3ria e os significados da P\u00e1scoa, bem como para desenvolver um senso de comunidade e empatia pelos outros. Aqui est\u00e1 esse lindo mural para voc\u00ea montar com sua turma, os alunos sempre gostam de expor seus trabalhos.<\/p>\n<p>Material <em><strong>n\u00e3o<\/strong><\/em> edit\u00e1vel com 22 p\u00e1ginas contendo:<\/p>\n<ul>\n<li>Coelho ampliado em 4 folhas A4;<\/li>\n<li>Bordas;<\/li>\n<li>Dois modelos de ovos de P\u00e1scoa para pintar (em dois tamanhos);<\/li>\n<li>Frase (ampliada) \u2013 Que sua P\u00e1scoa seja recheada de:<\/li>\n<\/ul>\n<p>O objetivo da atividade\/mural \u00e9 fazer com que os alunos escrevam palavras que representem referentes \u00e0 P\u00e1scoa.<\/p>\n<h3>N\u00e3o enviamos por e-mail, a entrega \u00e9 via link para download. \ud83d\udc47<\/h3>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33408 size-full\" src=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/02\/Aviso-Loja.jpg\" alt=\"\" width=\"446\" height=\"251\" srcset=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/02\/Aviso-Loja.jpg 446w, https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/02\/Aviso-Loja-300x169.jpg 300w, https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/02\/Aviso-Loja-18x10.jpg 18w\" sizes=\"auto, (max-width: 446px) 100vw, 446px\" \/><\/p>","protected":false},"featured_media":25826,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[122,123,124,125,127,216,218,210,214,212],"product_tag":[1258,1260,532,1262,633,1263,540,1259,1261,432],"class_list":{"0":"post-25794","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-1o-ano","7":"product_cat-2o-ano","8":"product_cat-3o-ano","9":"product_cat-4o-ano","10":"product_cat-5o-ano","11":"product_cat-data-comemorativa-4-ano","12":"product_cat-data-comemorativa-5-ano","13":"product_cat-data-comemorativa-1-ano","14":"product_cat-data-comemorativa-3-ano","15":"product_cat-data-comemorativa-2-ano","16":"product_tag-atividades-de-pascoa","17":"product_tag-coelho-ampliado","18":"product_tag-criatividade","19":"product_tag-decoracao-de-pascoa","20":"product_tag-escola","21":"product_tag-frase-interativa","22":"product_tag-material-educativo","23":"product_tag-mural-de-pascoa","24":"product_tag-ovos-para-pintar","25":"product_tag-pascoa","27":"first","28":"instock","29":"downloadable","30":"virtual","31":"sold-individually","32":"purchasable","33":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>P\u00e1scoa recheada - Loja SOS Professor Atividades<\/title>\n<meta name=\"description\" content=\"Arquivo em PDF n\u00e3o edit\u00e1vel com 22 p\u00e1ginas para atividades e mural de P\u00e1scoa. Cont\u00e9m coelho ampliado, bordas, ovos de P\u00e1scoa para pintar em dois tamanhos e frase ampliada para completar. Incentiva os alunos a escreverem palavras relacionadas \u00e0 P\u00e1scoa de forma criativa e interativa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/pascoa-recheada\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P\u00e1scoa recheada - Loja SOS Professor Atividades\" \/>\n<meta property=\"og:description\" content=\"Arquivo em PDF n\u00e3o edit\u00e1vel com 22 p\u00e1ginas para atividades e mural de P\u00e1scoa. Cont\u00e9m coelho ampliado, bordas, ovos de P\u00e1scoa para pintar em dois tamanhos e frase ampliada para completar. Incentiva os alunos a escreverem palavras relacionadas \u00e0 P\u00e1scoa de forma criativa e interativa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/pascoa-recheada\/\" \/>\n<meta property=\"og:site_name\" content=\"Loja SOS Professor Atividades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sosprofessoratividades\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T19:51:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/03\/1-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"693\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/pascoa-recheada\\\/\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/pascoa-recheada\\\/\",\"name\":\"P\u00e1scoa recheada - Loja SOS Professor Atividades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/pascoa-recheada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/pascoa-recheada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1-5.jpg\",\"datePublished\":\"2023-03-30T10:00:55+00:00\",\"dateModified\":\"2026-05-08T19:51:38+00:00\",\"description\":\"Arquivo em PDF n\u00e3o edit\u00e1vel com 22 p\u00e1ginas para atividades e mural de P\u00e1scoa. Cont\u00e9m coelho ampliado, bordas, ovos de P\u00e1scoa para pintar em dois tamanhos e frase ampliada para completar. Incentiva os alunos a escreverem palavras relacionadas \u00e0 P\u00e1scoa de forma criativa e interativa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/pascoa-recheada\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/pascoa-recheada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/pascoa-recheada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1-5.jpg\",\"contentUrl\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1-5.jpg\",\"width\":800,\"height\":693,\"caption\":\"P\u00e1scoa recheada\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/pascoa-recheada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"P\u00e1scoa recheada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#website\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\",\"name\":\"Loja SOS Professor Atividades\",\"description\":\"Venda de material did\u00e1tico para o ensino fundamental\",\"publisher\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#organization\",\"name\":\"Loja SOS Professor Atividades\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo.png\",\"contentUrl\":\"http:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo.png\",\"width\":2000,\"height\":2000,\"caption\":\"Loja SOS Professor Atividades\"},\"image\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sosprofessoratividades\",\"https:\\\/\\\/www.instagram.com\\\/sosprofessoratividades\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"P\u00e1scoa recheada - Loja SOS Professor Atividades","description":"Arquivo em PDF n\u00e3o edit\u00e1vel com 22 p\u00e1ginas para atividades e mural de P\u00e1scoa. Cont\u00e9m coelho ampliado, bordas, ovos de P\u00e1scoa para pintar em dois tamanhos e frase ampliada para completar. Incentiva os alunos a escreverem palavras relacionadas \u00e0 P\u00e1scoa de forma criativa e interativa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/pascoa-recheada\/","og_locale":"en_US","og_type":"article","og_title":"P\u00e1scoa recheada - Loja SOS Professor Atividades","og_description":"Arquivo em PDF n\u00e3o edit\u00e1vel com 22 p\u00e1ginas para atividades e mural de P\u00e1scoa. Cont\u00e9m coelho ampliado, bordas, ovos de P\u00e1scoa para pintar em dois tamanhos e frase ampliada para completar. Incentiva os alunos a escreverem palavras relacionadas \u00e0 P\u00e1scoa de forma criativa e interativa.","og_url":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/pascoa-recheada\/","og_site_name":"Loja SOS Professor Atividades","article_publisher":"https:\/\/www.facebook.com\/sosprofessoratividades","article_modified_time":"2026-05-08T19:51:38+00:00","og_image":[{"width":800,"height":693,"url":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/03\/1-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/pascoa-recheada\/","url":"https:\/\/lojasosprofessoratividades.com.br\/produto\/pascoa-recheada\/","name":"P\u00e1scoa recheada - Loja SOS Professor Atividades","isPartOf":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/pascoa-recheada\/#primaryimage"},"image":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/pascoa-recheada\/#primaryimage"},"thumbnailUrl":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/03\/1-5.jpg","datePublished":"2023-03-30T10:00:55+00:00","dateModified":"2026-05-08T19:51:38+00:00","description":"Arquivo em PDF n\u00e3o edit\u00e1vel com 22 p\u00e1ginas para atividades e mural de P\u00e1scoa. Cont\u00e9m coelho ampliado, bordas, ovos de P\u00e1scoa para pintar em dois tamanhos e frase ampliada para completar. Incentiva os alunos a escreverem palavras relacionadas \u00e0 P\u00e1scoa de forma criativa e interativa.","breadcrumb":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/pascoa-recheada\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lojasosprofessoratividades.com.br\/produto\/pascoa-recheada\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/pascoa-recheada\/#primaryimage","url":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/03\/1-5.jpg","contentUrl":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2023\/03\/1-5.jpg","width":800,"height":693,"caption":"P\u00e1scoa recheada"},{"@type":"BreadcrumbList","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/pascoa-recheada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lojasosprofessoratividades.com.br\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/lojasosprofessoratividades.com.br\/loja\/"},{"@type":"ListItem","position":3,"name":"P\u00e1scoa recheada"}]},{"@type":"WebSite","@id":"https:\/\/lojasosprofessoratividades.com.br\/#website","url":"https:\/\/lojasosprofessoratividades.com.br\/","name":"Loja SOS Professor Atividades","description":"Venda de material did\u00e1tico para o ensino fundamental","publisher":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lojasosprofessoratividades.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lojasosprofessoratividades.com.br\/#organization","name":"Loja SOS Professor Atividades","url":"https:\/\/lojasosprofessoratividades.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lojasosprofessoratividades.com.br\/#\/schema\/logo\/image\/","url":"http:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/04\/Logo.png","contentUrl":"http:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/04\/Logo.png","width":2000,"height":2000,"caption":"Loja SOS Professor Atividades"},"image":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sosprofessoratividades","https:\/\/www.instagram.com\/sosprofessoratividades\/"]}]}},"_links":{"self":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product\/25794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/comments?post=25794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/media\/25826"}],"wp:attachment":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/media?parent=25794"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_brand?post=25794"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=25794"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=25794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}