{"id":31151,"date":"2024-07-21T23:34:52","date_gmt":"2024-07-22T02:34:52","guid":{"rendered":"https:\/\/lojasosprofessoratividades.com.br\/?post_type=product&#038;p=31151"},"modified":"2026-05-08T16:11:39","modified_gmt":"2026-05-08T19:11:39","slug":"personagens-do-folclore","status":"publish","type":"product","link":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/personagens-do-folclore\/","title":{"rendered":"Personagens do Folclore"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Cont\u00e9m um total de <strong>88 p\u00e1ginas<\/strong>, incluindo <strong>9 personagens folcl\u00f3ricos <\/strong>ampliados em 9 folhas A4 cada\u00a0e <strong>\u00a0folhas para o t\u00edtulo do mural<\/strong>. Este recurso foi cuidadosamente desenvolvido para facilitar a montagem de um mural escolar tem\u00e1tico, proporcionando uma ferramenta visual e interativa para enriquecer o ambiente de aprendizagem dos alunos.<\/p>\n<p><strong>Acompanha tamb\u00e9m sugest\u00f5es de atividades para o 1\u00b0 ao 5\u00b0 ano do Ensino Fundamental 1<\/strong>, permitindo aos professores integrar essas figuras folcl\u00f3ricas em diversas din\u00e2micas pedag\u00f3gicas. As atividades s\u00e3o pensadas para desenvolver habilidades de leitura, escrita, interpreta\u00e7\u00e3o, criatividade e express\u00e3o corporal, com propostas l\u00fadicas e envolventes.<\/p>\n<p><strong>Benef\u00edcios do Arquivo &#8220;Personagens Folcl\u00f3ricos&#8221;:<\/strong><\/p>\n<ul>\n<li><strong>Imagens coloridas e ampliadas<\/strong> que capturam a imagina\u00e7\u00e3o dos alunos.<\/li>\n<li><strong>Facilidade na montagem<\/strong> de murais tem\u00e1ticos, transformando o espa\u00e7o escolar.<\/li>\n<li><strong>Sugest\u00f5es de atividades<\/strong> diversificadas que atendem diferentes faixas et\u00e1rias e objetivos pedag\u00f3gicos.<\/li>\n<li><strong>Incentivo ao conhecimento e valoriza\u00e7\u00e3o<\/strong> do folclore brasileiro, essencial para a forma\u00e7\u00e3o cultural dos estudantes.<\/li>\n<\/ul>\n<p>Aproveite este recurso com <em><strong>nossas imagens exclusivas<\/strong><\/em>, para tornar suas aulas mais din\u00e2micas e enriquecedoras!<\/p>\n<h3>N\u00e3o enviamos por e-mail, a entrega \u00e9 via link para download. \ud83d\udc47<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-30821 size-full\" src=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/06\/Aviso-Loja.jpg\" alt=\"\" width=\"446\" height=\"251\" srcset=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/06\/Aviso-Loja.jpg 446w, https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/06\/Aviso-Loja-300x169.jpg 300w, https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/06\/Aviso-Loja-18x10.jpg 18w\" sizes=\"auto, (max-width: 446px) 100vw, 446px\" \/><\/p>","protected":false},"featured_media":31154,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[122,123,124,125,127,216,218,214,210,212,126,211,217,213,209,215],"product_tag":[554,546,551,246,493,544,550,387,548,552],"class_list":{"0":"post-31151","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-1o-ano","7":"product_cat-2o-ano","8":"product_cat-3o-ano","9":"product_cat-4o-ano","10":"product_cat-5o-ano","11":"product_cat-data-comemorativa-4-ano","12":"product_cat-data-comemorativa-5-ano","13":"product_cat-data-comemorativa-3-ano","14":"product_cat-data-comemorativa-1-ano","15":"product_cat-data-comemorativa-2-ano","16":"product_cat-educacao-infantil","17":"product_cat-recursos-didaticos-2-ano","18":"product_cat-recursos-didaticos-5-ano","19":"product_cat-recursos-didaticos-3-ano","20":"product_cat-recursos-didaticos-1-ano","21":"product_cat-recursos-didaticos-4-ano","22":"product_tag-atividades-ludicas","23":"product_tag-atividades-pedagogicas","24":"product_tag-cultura-brasileira","25":"product_tag-educacao-infantil","26":"product_tag-ensino-fundamental-1","27":"product_tag-folclore-brasileiro","28":"product_tag-material-didatico","29":"product_tag-mural-escolar","30":"product_tag-personagens-folcloricos","31":"product_tag-recursos-educativos","33":"first","34":"instock","35":"downloadable","36":"virtual","37":"sold-individually","38":"purchasable","39":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Personagens do Folclore - Loja SOS Professor Atividades<\/title>\n<meta name=\"description\" content=\"Arquivo com 88 p\u00e1ginas sobre o folclore brasileiro: 9 personagens ampliados, sugest\u00f5es de atividades do 1\u00ba ao 5\u00ba ano, ideal para murais e aulas l\u00fadicas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/personagens-do-folclore\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Personagens do Folclore - Loja SOS Professor Atividades\" \/>\n<meta property=\"og:description\" content=\"Arquivo com 88 p\u00e1ginas sobre o folclore brasileiro: 9 personagens ampliados, sugest\u00f5es de atividades do 1\u00ba ao 5\u00ba ano, ideal para murais e aulas l\u00fadicas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/personagens-do-folclore\/\" \/>\n<meta property=\"og:site_name\" content=\"Loja SOS Professor Atividades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sosprofessoratividades\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T19:11:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/07\/1-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"693\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/personagens-do-folclore\\\/\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/personagens-do-folclore\\\/\",\"name\":\"Personagens do Folclore - Loja SOS Professor Atividades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/personagens-do-folclore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/personagens-do-folclore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1-4.jpg\",\"datePublished\":\"2024-07-22T02:34:52+00:00\",\"dateModified\":\"2026-05-08T19:11:39+00:00\",\"description\":\"Arquivo com 88 p\u00e1ginas sobre o folclore brasileiro: 9 personagens ampliados, sugest\u00f5es de atividades do 1\u00ba ao 5\u00ba ano, ideal para murais e aulas l\u00fadicas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/personagens-do-folclore\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/personagens-do-folclore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/personagens-do-folclore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1-4.jpg\",\"contentUrl\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/1-4.jpg\",\"width\":800,\"height\":693,\"caption\":\"Personagens do Folclore\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/personagens-do-folclore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Personagens do Folclore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#website\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\",\"name\":\"Loja SOS Professor Atividades\",\"description\":\"Venda de material did\u00e1tico para o ensino fundamental\",\"publisher\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#organization\",\"name\":\"Loja SOS Professor Atividades\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo.png\",\"contentUrl\":\"http:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo.png\",\"width\":2000,\"height\":2000,\"caption\":\"Loja SOS Professor Atividades\"},\"image\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sosprofessoratividades\",\"https:\\\/\\\/www.instagram.com\\\/sosprofessoratividades\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Personagens do Folclore - Loja SOS Professor Atividades","description":"Arquivo com 88 p\u00e1ginas sobre o folclore brasileiro: 9 personagens ampliados, sugest\u00f5es de atividades do 1\u00ba ao 5\u00ba ano, ideal para murais e aulas l\u00fadicas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/personagens-do-folclore\/","og_locale":"en_US","og_type":"article","og_title":"Personagens do Folclore - Loja SOS Professor Atividades","og_description":"Arquivo com 88 p\u00e1ginas sobre o folclore brasileiro: 9 personagens ampliados, sugest\u00f5es de atividades do 1\u00ba ao 5\u00ba ano, ideal para murais e aulas l\u00fadicas.","og_url":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/personagens-do-folclore\/","og_site_name":"Loja SOS Professor Atividades","article_publisher":"https:\/\/www.facebook.com\/sosprofessoratividades","article_modified_time":"2026-05-08T19:11:39+00:00","og_image":[{"width":800,"height":693,"url":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/07\/1-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/personagens-do-folclore\/","url":"https:\/\/lojasosprofessoratividades.com.br\/produto\/personagens-do-folclore\/","name":"Personagens do Folclore - Loja SOS Professor Atividades","isPartOf":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/personagens-do-folclore\/#primaryimage"},"image":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/personagens-do-folclore\/#primaryimage"},"thumbnailUrl":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/07\/1-4.jpg","datePublished":"2024-07-22T02:34:52+00:00","dateModified":"2026-05-08T19:11:39+00:00","description":"Arquivo com 88 p\u00e1ginas sobre o folclore brasileiro: 9 personagens ampliados, sugest\u00f5es de atividades do 1\u00ba ao 5\u00ba ano, ideal para murais e aulas l\u00fadicas.","breadcrumb":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/personagens-do-folclore\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lojasosprofessoratividades.com.br\/produto\/personagens-do-folclore\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/personagens-do-folclore\/#primaryimage","url":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/07\/1-4.jpg","contentUrl":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/07\/1-4.jpg","width":800,"height":693,"caption":"Personagens do Folclore"},{"@type":"BreadcrumbList","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/personagens-do-folclore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lojasosprofessoratividades.com.br\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/lojasosprofessoratividades.com.br\/loja\/"},{"@type":"ListItem","position":3,"name":"Personagens do Folclore"}]},{"@type":"WebSite","@id":"https:\/\/lojasosprofessoratividades.com.br\/#website","url":"https:\/\/lojasosprofessoratividades.com.br\/","name":"Loja SOS Professor Atividades","description":"Venda de material did\u00e1tico para o ensino fundamental","publisher":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lojasosprofessoratividades.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lojasosprofessoratividades.com.br\/#organization","name":"Loja SOS Professor Atividades","url":"https:\/\/lojasosprofessoratividades.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lojasosprofessoratividades.com.br\/#\/schema\/logo\/image\/","url":"http:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/04\/Logo.png","contentUrl":"http:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/04\/Logo.png","width":2000,"height":2000,"caption":"Loja SOS Professor Atividades"},"image":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sosprofessoratividades","https:\/\/www.instagram.com\/sosprofessoratividades\/"]}]}},"_links":{"self":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product\/31151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/comments?post=31151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/media\/31154"}],"wp:attachment":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/media?parent=31151"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_brand?post=31151"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=31151"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=31151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}