{"id":32990,"date":"2025-12-18T09:57:54","date_gmt":"2025-12-18T12:57:54","guid":{"rendered":"https:\/\/lojasosprofessoratividades.com.br\/?post_type=product&#038;p=32990"},"modified":"2026-05-08T14:11:32","modified_gmt":"2026-05-08T17:11:32","slug":"moana-capas-de-caderno","status":"publish","type":"product","link":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/moana-capas-de-caderno\/","title":{"rendered":"Moana &#8211; capas de caderno"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Deixe os cadernos dos seus alunos ainda mais especiais com o arquivo <strong>Moana &#8211; Capas de Caderno!<\/strong><\/p>\n<p>S\u00e3o <strong>13 modelos diferentes,<\/strong>\u00a0cada um com <strong>duas vers\u00f5es,<\/strong>\u00a0totalizando <strong>26 artes para escolher.<\/strong><\/p>\n<p><strong>I<\/strong><strong>magens dos personagens para colorir!<\/strong>\u00a0\ud83c\udfa8\ud83d\udd8c\ufe0f<\/p>\n<p>\ud83d\udcd6 <strong>Capas para:<\/strong><br \/>\n\ud83c\udfe0 Casa | \ud83c\udfeb Sala | \ud83d\ude4f Ensino Religioso | \ud83d\udd2c Ci\u00eancias | \ud83d\udcdc Hist\u00f3ria | \ud83c\udf0e Geografia | \ud83d\udcd6 Portugu\u00eas | \u270d\ufe0f Produ\u00e7\u00e3o de Texto | \u2797 Matem\u00e1tica | \ud83c\udfc3\u200d\u2642\ufe0fEd. F\u00edsica | \ud83c\uddec\ud83c\udde7 L\u00edngua Inglesa | \ud83c\udfad Arte | \ud83d\udcc5 Agenda<\/p>\n<p>\ud83d\udce5 <strong>Arquivo digital n\u00e3o edit\u00e1vel<\/strong> \u2013 pronto para imprimir e transformar o material escolar em uma verdadeira aventura!<\/p>\n<p>Garanta j\u00e1 o seu!<\/p>\n<h3><em><strong>N\u00e3o enviamos por e-mail, a entrega \u00e9 via link para download.\u00a0<img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/16.0.1\/svg\/1f447.svg\" alt=\"\ud83d\udc47\" \/><\/strong><\/em><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-32744 size-full\" src=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/12\/Aviso-Loja.jpg\" alt=\"\" width=\"446\" height=\"251\" srcset=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/12\/Aviso-Loja.jpg 446w, https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/12\/Aviso-Loja-300x169.jpg 300w, https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2024\/12\/Aviso-Loja-18x10.jpg 18w\" sizes=\"auto, (max-width: 446px) 100vw, 446px\" \/><\/p>","protected":false},"featured_media":32991,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[122,123,124,125,127,215,217,209,211,213],"product_tag":[750,616,1131,1129,1130,1133,493,718,643,1128,1132,236],"class_list":{"0":"post-32990","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-1o-ano","7":"product_cat-2o-ano","8":"product_cat-3o-ano","9":"product_cat-4o-ano","10":"product_cat-5o-ano","11":"product_cat-recursos-didaticos-4-ano","12":"product_cat-recursos-didaticos-5-ano","13":"product_cat-recursos-didaticos-1-ano","14":"product_cat-recursos-didaticos-2-ano","15":"product_cat-recursos-didaticos-3-ano","16":"product_tag-arquivo-digital","17":"product_tag-atividades-escolares","18":"product_tag-caderno-personalizado","19":"product_tag-capas-de-caderno","20":"product_tag-capas-escolares","21":"product_tag-decoracao-de-cadernos","22":"product_tag-ensino-fundamental-1","23":"product_tag-material-para-professores","24":"product_tag-material-pedagogico","25":"product_tag-moana","26":"product_tag-personagens-para-colorir","27":"product_tag-volta-as-aulas","29":"first","30":"instock","31":"downloadable","32":"virtual","33":"sold-individually","34":"purchasable","35":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Moana - capas de caderno - Loja SOS Professor Atividades<\/title>\n<meta name=\"description\" content=\"Arquivo Moana Capas de Caderno com 13 capas para o Fundamental 1, 26 artes para escolher e personagens para colorir. Material digital pronto para imprimir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/moana-capas-de-caderno\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moana - capas de caderno - Loja SOS Professor Atividades\" \/>\n<meta property=\"og:description\" content=\"Arquivo Moana Capas de Caderno com 13 capas para o Fundamental 1, 26 artes para escolher e personagens para colorir. Material digital pronto para imprimir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/moana-capas-de-caderno\/\" \/>\n<meta property=\"og:site_name\" content=\"Loja SOS Professor Atividades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sosprofessoratividades\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T17:11:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/01\/1-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"693\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/moana-capas-de-caderno\\\/\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/moana-capas-de-caderno\\\/\",\"name\":\"Moana - capas de caderno - Loja SOS Professor Atividades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/moana-capas-de-caderno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/moana-capas-de-caderno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/1-3.jpg\",\"datePublished\":\"2025-12-18T12:57:54+00:00\",\"dateModified\":\"2026-05-08T17:11:32+00:00\",\"description\":\"Arquivo Moana Capas de Caderno com 13 capas para o Fundamental 1, 26 artes para escolher e personagens para colorir. Material digital pronto para imprimir.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/moana-capas-de-caderno\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/moana-capas-de-caderno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/moana-capas-de-caderno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/1-3.jpg\",\"contentUrl\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/1-3.jpg\",\"width\":800,\"height\":693,\"caption\":\"Moana - capas de caderno\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/moana-capas-de-caderno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Moana &#8211; capas de caderno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#website\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\",\"name\":\"Loja SOS Professor Atividades\",\"description\":\"Venda de material did\u00e1tico para o ensino fundamental\",\"publisher\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#organization\",\"name\":\"Loja SOS Professor Atividades\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo.png\",\"contentUrl\":\"http:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo.png\",\"width\":2000,\"height\":2000,\"caption\":\"Loja SOS Professor Atividades\"},\"image\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sosprofessoratividades\",\"https:\\\/\\\/www.instagram.com\\\/sosprofessoratividades\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Moana - capas de caderno - Loja SOS Professor Atividades","description":"Arquivo Moana Capas de Caderno com 13 capas para o Fundamental 1, 26 artes para escolher e personagens para colorir. Material digital pronto para imprimir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/moana-capas-de-caderno\/","og_locale":"en_US","og_type":"article","og_title":"Moana - capas de caderno - Loja SOS Professor Atividades","og_description":"Arquivo Moana Capas de Caderno com 13 capas para o Fundamental 1, 26 artes para escolher e personagens para colorir. Material digital pronto para imprimir.","og_url":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/moana-capas-de-caderno\/","og_site_name":"Loja SOS Professor Atividades","article_publisher":"https:\/\/www.facebook.com\/sosprofessoratividades","article_modified_time":"2026-05-08T17:11:32+00:00","og_image":[{"width":800,"height":693,"url":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/01\/1-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/moana-capas-de-caderno\/","url":"https:\/\/lojasosprofessoratividades.com.br\/produto\/moana-capas-de-caderno\/","name":"Moana - capas de caderno - Loja SOS Professor Atividades","isPartOf":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/moana-capas-de-caderno\/#primaryimage"},"image":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/moana-capas-de-caderno\/#primaryimage"},"thumbnailUrl":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/01\/1-3.jpg","datePublished":"2025-12-18T12:57:54+00:00","dateModified":"2026-05-08T17:11:32+00:00","description":"Arquivo Moana Capas de Caderno com 13 capas para o Fundamental 1, 26 artes para escolher e personagens para colorir. Material digital pronto para imprimir.","breadcrumb":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/moana-capas-de-caderno\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lojasosprofessoratividades.com.br\/produto\/moana-capas-de-caderno\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/moana-capas-de-caderno\/#primaryimage","url":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/01\/1-3.jpg","contentUrl":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/01\/1-3.jpg","width":800,"height":693,"caption":"Moana - capas de caderno"},{"@type":"BreadcrumbList","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/moana-capas-de-caderno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lojasosprofessoratividades.com.br\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/lojasosprofessoratividades.com.br\/loja\/"},{"@type":"ListItem","position":3,"name":"Moana &#8211; capas de caderno"}]},{"@type":"WebSite","@id":"https:\/\/lojasosprofessoratividades.com.br\/#website","url":"https:\/\/lojasosprofessoratividades.com.br\/","name":"Loja SOS Professor Atividades","description":"Venda de material did\u00e1tico para o ensino fundamental","publisher":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lojasosprofessoratividades.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lojasosprofessoratividades.com.br\/#organization","name":"Loja SOS Professor Atividades","url":"https:\/\/lojasosprofessoratividades.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lojasosprofessoratividades.com.br\/#\/schema\/logo\/image\/","url":"http:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/04\/Logo.png","contentUrl":"http:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/04\/Logo.png","width":2000,"height":2000,"caption":"Loja SOS Professor Atividades"},"image":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sosprofessoratividades","https:\/\/www.instagram.com\/sosprofessoratividades\/"]}]}},"_links":{"self":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product\/32990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/comments?post=32990"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/media\/32991"}],"wp:attachment":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/media?parent=32990"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_brand?post=32990"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=32990"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=32990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}