{"id":33597,"date":"2026-01-18T06:43:41","date_gmt":"2026-01-18T09:43:41","guid":{"rendered":"https:\/\/lojasosprofessoratividades.com.br\/?post_type=product&#038;p=33597"},"modified":"2026-05-08T14:06:48","modified_gmt":"2026-05-08T17:06:48","slug":"carmen-miranda-a-pequena-notavel","status":"publish","type":"product","link":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/carmen-miranda-a-pequena-notavel\/","title":{"rendered":"Carmen Miranda &#8211; A Pequena Not\u00e1vel"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p data-start=\"69\" data-end=\"237\">Leve para sua sala de aula a hist\u00f3ria da grande estrela brasileira que conquistou o mundo!<\/p>\n<p data-start=\"69\" data-end=\"237\">Nosso material foi planejado para turmas do <strong data-start=\"209\" data-end=\"225\">4\u00ba e 5\u00ba anos<\/strong> e cont\u00e9m:<\/p>\n<p data-start=\"239\" data-end=\"510\">\u2705 <strong data-start=\"241\" data-end=\"272\">Biografia de Carmen Miranda<\/strong>\u00a0<br data-start=\"275\" data-end=\"278\" \/>\u2705 <strong data-start=\"280\" data-end=\"315\">Atividade de produ\u00e7\u00e3o de resumo<\/strong>\u00a0<br data-start=\"318\" data-end=\"321\" \/>\u2705 <strong data-start=\"323\" data-end=\"357\">QR Code com m\u00fasicas da artista<\/strong><br data-start=\"360\" data-end=\"363\" \/>\u2705 <strong data-start=\"365\" data-end=\"421\">Interpreta\u00e7\u00e3o do poema da m\u00fasica &#8220;Tico-Tico no Fub\u00e1&#8221;<\/strong>\u00a0<br data-start=\"424\" data-end=\"427\" data-is-only-node=\"\" \/>\u2705 <strong data-start=\"429\" data-end=\"455\">Plano de aula completo<\/strong>\u00a0<br data-start=\"458\" data-end=\"461\" \/>\u2705 <strong data-start=\"463\" data-end=\"485\">Imagens da artista<\/strong>\u00a0<br data-start=\"488\" data-end=\"491\" \/>\u2705 <strong data-start=\"493\" data-end=\"505\">Gabarito<\/strong><\/p>\n<p data-start=\"512\" data-end=\"604\">Um arquivo interativo e envolvente para ensinar cultura e m\u00fasica de forma divertida!<\/p>\n<p data-start=\"606\" data-end=\"707\"><strong data-start=\"609\" data-end=\"641\">Arquivo digital n\u00e3o edit\u00e1vel<\/strong>.<\/p>\n<p data-start=\"606\" data-end=\"707\">Adquira agora e leve mais hist\u00f3ria e arte para seus alunos!<\/p>\n<h3>N\u00e3o enviamos por e-mail, a entrega \u00e9 via link para download.\u00a0<img decoding=\"async\" class=\"emoji\" role=\"img\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f447.svg\" alt=\"\ud83d\udc47\" \/><\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-33408 size-full\" src=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/02\/Aviso-Loja.jpg\" alt=\"\" width=\"446\" height=\"251\" srcset=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/02\/Aviso-Loja.jpg 446w, https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/02\/Aviso-Loja-300x169.jpg 300w, https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/02\/Aviso-Loja-18x10.jpg 18w\" sizes=\"auto, (max-width: 446px) 100vw, 446px\" \/><\/p>","protected":false},"featured_media":33599,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[125,127,216,218,195,204,215,217],"product_tag":[253,248,3499,1226,3500,3503,1165,579,279,1225,506,3501,1223,551,245,3504,250,643,822,1224,398,1228,1229,1227,3502],"class_list":{"0":"post-33597","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-4o-ano","7":"product_cat-5o-ano","8":"product_cat-data-comemorativa-4-ano","9":"product_cat-data-comemorativa-5-ano","10":"product_cat-portugues-4-ano","11":"product_cat-portugues-5-anos","12":"product_cat-recursos-didaticos-4-ano","13":"product_cat-recursos-didaticos-5-ano","14":"product_tag-4o-ano","15":"product_tag-5o-ano","16":"product_tag-a-pequena-notavel","17":"product_tag-arte-e-musica","18":"product_tag-atividades-carmen-miranda","19":"product_tag-atividades-com-musica","20":"product_tag-atividades-de-portugues","21":"product_tag-atividades-educativas","22":"product_tag-atividades-interativas","23":"product_tag-aula-de-historia","24":"product_tag-biografia","25":"product_tag-biografia-carmen-miranda","26":"product_tag-carmen-miranda","27":"product_tag-cultura-brasileira","28":"product_tag-ensino-fundamental","29":"product_tag-historia-da-musica-brasileira","30":"product_tag-interpretacao-de-texto","31":"product_tag-material-pedagogico","32":"product_tag-musica-brasileira","33":"product_tag-pequena-notavel","34":"product_tag-plano-de-aula","35":"product_tag-poesia","36":"product_tag-producao-de-resumo","37":"product_tag-qr-code","38":"product_tag-tico-tico-no-fuba","40":"first","41":"instock","42":"downloadable","43":"virtual","44":"sold-individually","45":"purchasable","46":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carmen Miranda - A Pequena Not\u00e1vel - Loja SOS Professor Atividades<\/title>\n<meta name=\"description\" content=\"Arquivo Carmen Miranda \u2013 A Pequena Not\u00e1vel para 4\u00ba e 5\u00ba ano, com biografia, atividades, m\u00fasica Tico-Tico no Fub\u00e1, QR Code, plano de aula e gabarito.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/carmen-miranda-a-pequena-notavel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carmen Miranda - A Pequena Not\u00e1vel - Loja SOS Professor Atividades\" \/>\n<meta property=\"og:description\" content=\"Arquivo Carmen Miranda \u2013 A Pequena Not\u00e1vel para 4\u00ba e 5\u00ba ano, com biografia, atividades, m\u00fasica Tico-Tico no Fub\u00e1, QR Code, plano de aula e gabarito.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/carmen-miranda-a-pequena-notavel\/\" \/>\n<meta property=\"og:site_name\" content=\"Loja SOS Professor Atividades\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sosprofessoratividades\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T17:06:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/02\/1-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"693\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/carmen-miranda-a-pequena-notavel\\\/\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/carmen-miranda-a-pequena-notavel\\\/\",\"name\":\"Carmen Miranda - A Pequena Not\u00e1vel - Loja SOS Professor Atividades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/carmen-miranda-a-pequena-notavel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/carmen-miranda-a-pequena-notavel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/1-5.jpg\",\"datePublished\":\"2026-01-18T09:43:41+00:00\",\"dateModified\":\"2026-05-08T17:06:48+00:00\",\"description\":\"Arquivo Carmen Miranda \u2013 A Pequena Not\u00e1vel para 4\u00ba e 5\u00ba ano, com biografia, atividades, m\u00fasica Tico-Tico no Fub\u00e1, QR Code, plano de aula e gabarito.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/carmen-miranda-a-pequena-notavel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/carmen-miranda-a-pequena-notavel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/carmen-miranda-a-pequena-notavel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/1-5.jpg\",\"contentUrl\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/1-5.jpg\",\"width\":800,\"height\":693,\"caption\":\"Carmen Miranda - A Pequena Not\u00e1vel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/produto\\\/carmen-miranda-a-pequena-notavel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Carmen Miranda &#8211; A Pequena Not\u00e1vel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#website\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\",\"name\":\"Loja SOS Professor Atividades\",\"description\":\"Venda de material did\u00e1tico para o ensino fundamental\",\"publisher\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#organization\",\"name\":\"Loja SOS Professor Atividades\",\"url\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo.png\",\"contentUrl\":\"http:\\\/\\\/lojasosprofessoratividades.com.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo.png\",\"width\":2000,\"height\":2000,\"caption\":\"Loja SOS Professor Atividades\"},\"image\":{\"@id\":\"https:\\\/\\\/lojasosprofessoratividades.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sosprofessoratividades\",\"https:\\\/\\\/www.instagram.com\\\/sosprofessoratividades\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carmen Miranda - A Pequena Not\u00e1vel - Loja SOS Professor Atividades","description":"Arquivo Carmen Miranda \u2013 A Pequena Not\u00e1vel para 4\u00ba e 5\u00ba ano, com biografia, atividades, m\u00fasica Tico-Tico no Fub\u00e1, QR Code, plano de aula e gabarito.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/carmen-miranda-a-pequena-notavel\/","og_locale":"en_US","og_type":"article","og_title":"Carmen Miranda - A Pequena Not\u00e1vel - Loja SOS Professor Atividades","og_description":"Arquivo Carmen Miranda \u2013 A Pequena Not\u00e1vel para 4\u00ba e 5\u00ba ano, com biografia, atividades, m\u00fasica Tico-Tico no Fub\u00e1, QR Code, plano de aula e gabarito.","og_url":"https:\/\/lojasosprofessoratividades.com.br\/en\/product\/carmen-miranda-a-pequena-notavel\/","og_site_name":"Loja SOS Professor Atividades","article_publisher":"https:\/\/www.facebook.com\/sosprofessoratividades","article_modified_time":"2026-05-08T17:06:48+00:00","og_image":[{"width":800,"height":693,"url":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/02\/1-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/carmen-miranda-a-pequena-notavel\/","url":"https:\/\/lojasosprofessoratividades.com.br\/produto\/carmen-miranda-a-pequena-notavel\/","name":"Carmen Miranda - A Pequena Not\u00e1vel - Loja SOS Professor Atividades","isPartOf":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/carmen-miranda-a-pequena-notavel\/#primaryimage"},"image":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/carmen-miranda-a-pequena-notavel\/#primaryimage"},"thumbnailUrl":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/02\/1-5.jpg","datePublished":"2026-01-18T09:43:41+00:00","dateModified":"2026-05-08T17:06:48+00:00","description":"Arquivo Carmen Miranda \u2013 A Pequena Not\u00e1vel para 4\u00ba e 5\u00ba ano, com biografia, atividades, m\u00fasica Tico-Tico no Fub\u00e1, QR Code, plano de aula e gabarito.","breadcrumb":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/carmen-miranda-a-pequena-notavel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lojasosprofessoratividades.com.br\/produto\/carmen-miranda-a-pequena-notavel\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/carmen-miranda-a-pequena-notavel\/#primaryimage","url":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/02\/1-5.jpg","contentUrl":"https:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2025\/02\/1-5.jpg","width":800,"height":693,"caption":"Carmen Miranda - A Pequena Not\u00e1vel"},{"@type":"BreadcrumbList","@id":"https:\/\/lojasosprofessoratividades.com.br\/produto\/carmen-miranda-a-pequena-notavel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/lojasosprofessoratividades.com.br\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/lojasosprofessoratividades.com.br\/loja\/"},{"@type":"ListItem","position":3,"name":"Carmen Miranda &#8211; A Pequena Not\u00e1vel"}]},{"@type":"WebSite","@id":"https:\/\/lojasosprofessoratividades.com.br\/#website","url":"https:\/\/lojasosprofessoratividades.com.br\/","name":"Loja SOS Professor Atividades","description":"Venda de material did\u00e1tico para o ensino fundamental","publisher":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lojasosprofessoratividades.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lojasosprofessoratividades.com.br\/#organization","name":"Loja SOS Professor Atividades","url":"https:\/\/lojasosprofessoratividades.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lojasosprofessoratividades.com.br\/#\/schema\/logo\/image\/","url":"http:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/04\/Logo.png","contentUrl":"http:\/\/lojasosprofessoratividades.com.br\/wp-content\/uploads\/2022\/04\/Logo.png","width":2000,"height":2000,"caption":"Loja SOS Professor Atividades"},"image":{"@id":"https:\/\/lojasosprofessoratividades.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sosprofessoratividades","https:\/\/www.instagram.com\/sosprofessoratividades\/"]}]}},"_links":{"self":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product\/33597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/comments?post=33597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/media\/33599"}],"wp:attachment":[{"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/media?parent=33597"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_brand?post=33597"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=33597"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lojasosprofessoratividades.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=33597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}